{"id":2529,"date":"2023-10-30T10:05:08","date_gmt":"2023-10-30T10:05:08","guid":{"rendered":"https:\/\/elearning.ddasproject.eu\/gender-based-violence-at-school\/"},"modified":"2024-05-31T10:55:52","modified_gmt":"2024-05-31T10:55:52","slug":"gender-based-violence-at-school","status":"publish","type":"page","link":"https:\/\/elearning.ddasproject.eu\/fr\/gender-based-violence-at-school\/","title":{"rendered":"Violence fond\u00e9e sur le genre \u00e0 l&rsquo;\u00e9cole"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbDoctors\u00a0\u00bb _builder_version=\u00a0\u00bb4.21.2&Prime; custom_padding=\u00a0\u00bb0px||3px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row padding_top_bottom_link_1=\u00a0\u00bbtrue\u00a0\u00bb padding_left_right_link_1=\u00a0\u00bbtrue\u00a0\u00bb _builder_version=\u00a0\u00bb4.21.2&Prime; background_enable_color=\u00a0\u00bboff\u00a0\u00bb use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_direction=\u00a0\u00bb140deg\u00a0\u00bb background_color_gradient_stops=\u00a0\u00bb#70277d 0%|rgba(112,39,125,0.55) 100%\u00a0\u00bb background_color_gradient_start=\u00a0\u00bb#62de9d\u00a0\u00bb custom_margin=\u00a0\u00bb0px||60px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb100px|30px|100px|30px|true|true\u00a0\u00bb animation_style=\u00a0\u00bbflip\u00a0\u00bb border_radii=\u00a0\u00bb|60px||60px|\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset3&Prime; box_shadow_vertical=\u00a0\u00bb45px\u00a0\u00bb box_shadow_blur=\u00a0\u00bb42px\u00a0\u00bb box_shadow_spread=\u00a0\u00bb-26px\u00a0\u00bb box_shadow_color=\u00a0\u00bbrgba(112,39,125,0.59)\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_post_title meta=\u00a0\u00bboff\u00a0\u00bb featured_image=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_level=\u00a0\u00bbh2&Prime; title_font=\u00a0\u00bbRoboto|700|||||||\u00a0\u00bb title_text_align=\u00a0\u00bbcenter\u00a0\u00bb title_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb title_font_size=\u00a0\u00bb30px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb title_2_font_size_tablet=\u00a0\u00bb30px\u00a0\u00bb title_2_font_size_phone=\u00a0\u00bb22px\u00a0\u00bb title_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb][\/et_pb_post_title][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_3_text_color=\u00a0\u00bb#6F277C\u00a0\u00bb border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Une activit\u00e9 bas\u00e9e sur un sc\u00e9nario aidant les enseignants \u00e0 comprendre en pratique diff\u00e9rents aspects li\u00e9s au genre.<\/h3>\n<p>Une activit\u00e9 bas\u00e9e sur des sc\u00e9narios permettant aux enseignants de mieux appr\u00e9hender en pratique les diff\u00e9rents concepts li\u00e9s au genre et aux st\u00e9r\u00e9otypes, ainsi que la violence qui y est associ\u00e9e et qui peut survenir \u00e0 l&rsquo;\u00e9cole.<\/p>\n<ul><\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_color=\u00a0\u00bb#949e38&Prime; header_2_text_color=\u00a0\u00bb#949e38&Prime; border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Objectifs<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#x3d;||divi||400&Prime; icon_color=\u00a0\u00bb#949e38&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Mieux comprendre les notions de genre, les st\u00e9r\u00e9otypes et la violence dans les \u00e9tablissements scolaires, ses diff\u00e9rentes manifestations et les causes qui les sous-tendent.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#x3d;||divi||400&Prime; icon_color=\u00a0\u00bb#949e38&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>D\u00e9velopper de l&#8217;empathie pour ceux qui en font directement l&rsquo;exp\u00e9rience.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_blurb use_icon=\u00a0\u00bbon\u00a0\u00bb font_icon=\u00a0\u00bb&#x3d;||divi||400&Prime; icon_color=\u00a0\u00bb#949e38&Prime; icon_placement=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Discuter des moyens d&rsquo;aborder, en tant qu&rsquo;enseignant, les attitudes et les comportements abusifs \u00e0 l&rsquo;\u00e9cole.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,2_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_color=\u00a0\u00bb#949e38&Prime; header_2_text_color=\u00a0\u00bb#949e38&Prime; border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Dur\u00e9e indicative\u00a0<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>60 minutes<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,2_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_color=\u00a0\u00bb#949e38&Prime; header_2_text_color=\u00a0\u00bb#949e38&Prime; border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Facilitateur et groupe cible<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span style=\"font-weight: 400;\">Facilitateur(s) : un ou plusieurs instructeurs<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Groupe cible : enseignants\/personnel scolaire<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,2_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_color=\u00a0\u00bb#949e38&Prime; header_2_text_color=\u00a0\u00bb#949e38&Prime; border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Pr\u00e9paration pour l&rsquo;enseignant<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb link_font=\u00a0\u00bb||||on||||\u00a0\u00bb border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span style=\"font-weight: 400;\">Imprimez les scenarios<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Expliquez que l&rsquo;activit\u00e9 permettra d&rsquo;explorer les id\u00e9es li\u00e9es au genre et aux st\u00e9r\u00e9otypes qui y sont associ\u00e9s, ainsi que les cas de violence fond\u00e9es sur le genre qui peuvent se produire \u00e0 l&rsquo;\u00e9cole, \u00e0 travers des sc\u00e9narios de brimades\/harc\u00e8lement fond\u00e9s sur le genre. L&rsquo;objectif est de comprendre pourquoi la violence survient, comment elle peut affecter la personne qui la subit et comment nous pouvons r\u00e9agir \u00e0 ce type d&rsquo;incidents.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_color=\u00a0\u00bb#949e38&Prime; header_2_text_color=\u00a0\u00bb#949e38&Prime; border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>M\u00e9thodologie &#8211; \u00e9tapes<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_4,3_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bb|800|||||||\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_text_color=\u00a0\u00bb#E09900&Prime; header_font_size=\u00a0\u00bb25px\u00a0\u00bb border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1><strong>1.<\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||20px||false|false\u00a0\u00bb border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bb#949e38&Prime; border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span style=\"font-weight: 400;\">R\u00e9partissez les participants en paires ou en petits groupes, puis s\u00e9lectionnez quelques-uns des sc\u00e9narios suivants et distribuez-en un \u00e0 chaque groupe.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_4,3_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bb|800|||||||\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_text_color=\u00a0\u00bb#E09900&Prime; header_font_size=\u00a0\u00bb25px\u00a0\u00bb border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1><strong>2.<\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text ol_type=\u00a0\u00bblower-latin\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||20px||false|false\u00a0\u00bb border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bb#949e38&Prime; border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span style=\"font-weight: 400;\">Demandez aux groupes de d\u00e9battre du sc\u00e9nario en exprimant, un par un, leurs opinions en essayant de r\u00e9pondre aux questions suivantes :<\/span><\/p>\n<ol>\n<li>\u00a0Quels sont les \u00e9l\u00e9ments de genre qui interviennent dans ce sc\u00e9nario ? Pouvez-vous identifier, \u00e0 partir du sc\u00e9nario, le sexe assign\u00e9 \u00e0 la naissance, l&rsquo;identit\u00e9 de genre, l&rsquo;orientation sexuelle et l&rsquo;expression de genre des personnages pr\u00e9sent\u00e9s ?<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Avez-vous connaissance d&rsquo;un sc\u00e9nario similaire dans votre \u00e9cole ?<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Que pensez-vous de cette situation ?<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Comment pensez-vous que la personne impliqu\u00e9e se sent ?<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Que feriez-vous dans cette situation ?<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Que pourrait-on faire pour \u00e9viter ce genre de situation ?<\/span><\/li>\n<\/ol>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_4,3_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bb|800|||||||\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_text_color=\u00a0\u00bb#E09900&Prime; header_font_size=\u00a0\u00bb25px\u00a0\u00bb border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1><strong>3.<\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text ol_type=\u00a0\u00bblower-latin\u00a0\u00bb _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||20px||false|false\u00a0\u00bb border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bb#949e38&Prime; border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span style=\"font-weight: 400;\">En s\u00e9ance pl\u00e9ni\u00e8re, chaque groupe pr\u00e9sente son sc\u00e9nario et les pistes d\u00e9velopp\u00e9es aux autres.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_4,3_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bb|800|||||||\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_text_color=\u00a0\u00bb#E09900&Prime; header_font_size=\u00a0\u00bb25px\u00a0\u00bb border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1><strong>4.<\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text ol_type=\u00a0\u00bblower-latin\u00a0\u00bb _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||20px||false|false\u00a0\u00bb border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bb#949e38&Prime; border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span style=\"font-weight: 400;\">L&rsquo;ensemble du groupe discute des principes d&rsquo;une politique scolaire plus inclusive pour pr\u00e9venir et traiter les st\u00e9r\u00e9otypes et la violence fond\u00e9s sur le genre.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_4,3_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bb|800|||||||\u00a0\u00bb header_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_text_color=\u00a0\u00bb#E09900&Prime; header_font_size=\u00a0\u00bb25px\u00a0\u00bb border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1><strong>5.<\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text ol_type=\u00a0\u00bblower-latin\u00a0\u00bb _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||20px||false|false\u00a0\u00bb border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bb#949e38&Prime; border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span style=\"font-weight: 400;\">Encouragez tous les participants \u00e0 donner leur avis sur les r\u00e9sultats des autres groupes. Demandez \u00e0 tous les participants de r\u00e9fl\u00e9chir : votre opinion a-t-elle chang\u00e9 au cours de l&rsquo;activit\u00e9 ? Avez-vous pu trouver des \u00e9l\u00e9ments int\u00e9ressants ?\u00a0<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,2_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_color=\u00a0\u00bb#949e38&Prime; header_2_text_color=\u00a0\u00bb#949e38&Prime; border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>D\u00e9briefing et \u00e9valuation<\/h2>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.23&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb link_font=\u00a0\u00bb||||on||||\u00a0\u00bb border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Prenez des notes, en tant que facilitateur, en cr\u00e9ant des lignes directrices de base et des bonnes pratiques pour pr\u00e9venir et pour r\u00e9pondre \u00e0 des cas similaires li\u00e9s \u00e0 la discrimination fond\u00e9e sur le genre dans le cadre scolaire.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,2_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_color=\u00a0\u00bb#949e38&Prime; header_2_text_color=\u00a0\u00bb#949e38&Prime; border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>R\u00e9f\u00e9rences\/ sources :<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb link_font=\u00a0\u00bb||||on||||\u00a0\u00bb border_style_bottom=\u00a0\u00bbdashed\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Projet Erasmus+ \u201cFREE from gender-based discrimination: Teachers and parents together (2019-1-UK01-KA201-062092) <\/span><a href=\"https:\/\/www.projectfree.eu\/\"><span style=\"font-weight: 400;\">https:\/\/www.projectfree.eu<\/span><\/a><span style=\"font-weight: 400;\">\u00a0\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Conseil de l&rsquo;Europe \u201cGender Matters\u201d: <\/span><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.coe.int\/en\/web\/gender-matters\/activities\">https:\/\/www.coe.int\/en\/web\/gender-matters\/activities<\/a><a href=\"https:\/\/www.coe.int\/en\/web\/gender-matters\/activities\"><\/a><\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">YSAFE.NET: <a href=\"https:\/\/ysafe.net\/ippf\/toolkit\/part-03\/chapter-10\/activity-10-07\/stories-of-gender-based-violence\/\"><span>https:\/\/ysafe.net\/ippf\/toolkit\/part-03\/chapter-10\/activity-10-07\/stories-of-gender-based-violence\/<\/span><\/a><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bbhttps:\/\/elearning.ddasproject.eu\/wp-content\/uploads\/5.-DD@S_Module4_Activity2_Handout-fr.docx.pdf\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbDocument\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_bg_color=\u00a0\u00bb#949e38&Prime; background_layout=\u00a0\u00bbdark\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;][\/et_pb_button][et_pb_button button_url=\u00a0\u00bbhttps:\/\/elearning.ddasproject.eu\/wp-content\/uploads\/4.-DD@S_-Module4_Activity2_Scenario_forTeachers-fr.docx.pdf\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbPDF Version\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.3&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_bg_color=\u00a0\u00bb#949e38&Prime; background_layout=\u00a0\u00bbdark\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9zZndkLWNvdXJzZXMiLCJzZXR0aW5ncyI6eyJwb3N0X2lkIjoiNzMifX0=@\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbRetour au module\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.3&Prime; _dynamic_attributes=\u00a0\u00bbbutton_url\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_bg_color=\u00a0\u00bb#6f277c\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une activit\u00e9 bas\u00e9e sur un sc\u00e9nario aidant les enseignants \u00e0 comprendre en pratique diff\u00e9rents aspects li\u00e9s au genre. Une activit\u00e9 bas\u00e9e sur des sc\u00e9narios permettant aux enseignants de mieux appr\u00e9hender en pratique les diff\u00e9rents concepts li\u00e9s au genre et aux st\u00e9r\u00e9otypes, ainsi que la violence qui y est associ\u00e9e et qui peut survenir \u00e0 l&rsquo;\u00e9cole. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"class_list":["post-2529","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/elearning.ddasproject.eu\/fr\/wp-json\/wp\/v2\/pages\/2529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elearning.ddasproject.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elearning.ddasproject.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elearning.ddasproject.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elearning.ddasproject.eu\/fr\/wp-json\/wp\/v2\/comments?post=2529"}],"version-history":[{"count":4,"href":"https:\/\/elearning.ddasproject.eu\/fr\/wp-json\/wp\/v2\/pages\/2529\/revisions"}],"predecessor-version":[{"id":5597,"href":"https:\/\/elearning.ddasproject.eu\/fr\/wp-json\/wp\/v2\/pages\/2529\/revisions\/5597"}],"wp:attachment":[{"href":"https:\/\/elearning.ddasproject.eu\/fr\/wp-json\/wp\/v2\/media?parent=2529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}